{"id":14675,"date":"2012-04-11T10:46:36","date_gmt":"2012-04-11T15:46:36","guid":{"rendered":"http:\/\/www.austincnm.com\/?p=14675"},"modified":"2012-04-11T10:46:36","modified_gmt":"2012-04-11T15:46:36","slug":"estamos-muy-contentos","status":"publish","type":"post","link":"https:\/\/atxcatholic.com\/index.php\/2012\/04\/estamos-muy-contentos\/","title":{"rendered":"\u00a1Estamos Muy Contentos!"},"content":{"rendered":"<p>Esta conversaci\u00f3n de Cantinflas en la pel\u00edcula <em>El Padrecito<\/em> siempre me da risa por la forma en que Cantinflas explica su buen humor.\u00a0 Acaba de llegar Cantinflas como el nuevo padrecito a un pueblo y Don Silvestre (el antagonista de la pel\u00edcula) lo quiere correr de ah\u00ed porque sabe que puede interrumpir sus malas intenciones.<\/p>\n<p><strong>Don Silvestre: <\/strong>(hablando del padrecito) Mira, si hasta tiene buen humor, eh!<\/p>\n<p><strong>Cantinflas:<\/strong> \u00bfQue usted pensaba que los curas somos tristes?<\/p>\n<p><strong>Don Silvestre:<\/strong> No, no se, pero, como les crucificaron a su Dios. . .<\/p>\n<p><strong>Cantinflas:<\/strong> Si, pero f\u00edjese que ya <span style=\"text-decoration: underline;\">recusit\u00f3<\/span>, y estamos <em>muy<\/em> contentos!<\/p>\n<p>\u00a1Y as\u00ed estamos \u2013 muy contentos!\u00a0 Acabamos de celebrar la Resurrecci\u00f3n de Jes\u00fas.\u00a0 \u00a1Que alegr\u00eda! \u00a1Que esperanza!\u00a0 Hemos pasado la temporada de cuaresma donde nos enfocamos en intensa preparaci\u00f3n para caminar junto a Jes\u00fas durante 40 d\u00edas y celebramos Semana Santa donde recordamos su dolorosa Pasi\u00f3n.\u00a0 \u00a1Ha llegado la temporada de Pascua!<\/p>\n<p><a href=\"http:\/\/www.austincnm.com\/index.php\/2012\/04\/estamos-muy-contentos\/833762_easter_egg_2-2\/\" rel=\"attachment wp-att-14677\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-14677\" title=\"833762_easter_egg_2\" src=\"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2012\/04\/833762_easter_egg_21.jpg?resize=315%2C236\" alt=\"\" width=\"315\" height=\"236\" \/><\/a><\/p>\n<p>Algunos celebramos la misa de vigilia el s\u00e1bado por la noche donde observamos la solemnidad de la celebraci\u00f3n con velas y oscuridad,\u00a0 escuchamos varias historias del Antiguo Testamento, \u00a0y luego con luz vemos a todos los nuevos cat\u00f3licos bautizados y que entran en comuni\u00f3n con la Iglesia. Renovamos las promesas de nuestro bautismo y claro escuchamos el Evangelio que cuenta la historia de la resurrecci\u00f3n de nuestro Cristo.\u00a0 Es la misa de todas las misas que dura 2, 3,. . .y hasta 4 horas.<\/p>\n<p>Otros celebremos la misa el Domingo de Resurrecci\u00f3n y al igual es un a misa hermosa llena de todo lo que representa nuestra fe.\u00a0 En todas las misas recordamos que sin la resurrecci\u00f3n, nuestra fe, no tendr\u00eda mucho sentido.\u00a0 Al saber que Jes\u00fas venci\u00f3 la muerte y nos prepara una vida eterna con el, no se puede evitar sentir una inmensa alegr\u00eda y emoci\u00f3n.<\/p>\n<p>A mi personalmente me dio tanta alegr\u00eda saber que ese pedacito de cielo que vivimos en la misa es solo una muestra peque\u00f1a de la gloria del Reino de Dios.\u00a0 \u00a1Que hermoso ser\u00e1 poder estar juntos todos un d\u00eda con \u00c9l por una eternidad! \u00a0Antes dec\u00eda que la Navidad era mi celebraci\u00f3n favorita por toda la alegr\u00eda y paz de celebrar el nacimiento de Jes\u00fas, pero la felicidad de la Pascua es algo que sobrepasa toda celebraci\u00f3n y temporada.\u00a0 \u00a1Se cumpli\u00f3 la misi\u00f3n de Jes\u00fas y nos ha redimido!\u00a0 Y esto lo hizo aun sabiendo todos nuestros pecados.\u00a0 Nos mostro lo que es el amor.\u00a0 Por eso la cruz tiene tanto significado para nosotros \u2013 por lo que representa.\u00a0 \u00a1Wow! &#8211; ojala que nunca dejemos de sentir gran alegr\u00eda en cada Domingo de Resurrecci\u00f3n en nuestras vidas.\u00a0 Es la celebraci\u00f3n y d\u00eda festivo m\u00e1s importante para nosotros.<\/p>\n<p>Pero. . . .espera . . .no se ha terminado la Pascua.\u00a0 \u00a1No, porque en la Iglesia celebramos Pascua por 50 D\u00edas! Por siete semanas recordamos las escrituras del libro de los Hechos hasta que celebramos Pentecost\u00e9s cuando Dios mando al Esp\u00edritu Santo (el Par\u00e1clito del cual les hablo a los disc\u00edpulos en el libro de Juan capitulo 16).\u00a0<a href=\"http:\/\/www.austincnm.com\/index.php\/2012\/04\/estamos-muy-contentos\/candle\/\" rel=\"attachment wp-att-14678\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-14678\" title=\"candle\" src=\"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2012\/04\/candle-154x300.jpg?resize=154%2C300\" alt=\"\" width=\"154\" height=\"300\" \/><\/a> Empez\u00f3 la Evangelizaci\u00f3n de la Iglesia ese d\u00eda.\u00a0 En esta temporada reflejamos en lo que hay que hacer con esta nueva vida que nos ha regalado Jes\u00fas.\u00a0 Es la luz que tenemos que llevar a todo el mundo.\u00a0 Lo maravilloso es que sabemos que la oscuridad nunca apagar\u00e1 esa luz.\u00a0 Por m\u00e1s problemas, obst\u00e1culos, sufrimiento que veamos en este mundo, sabemos que en la guerra ya hay victoria.\u00a0 Las escrituras nos recuerdan de esta gran verdad.\u00a0 Renovamos nuestras promesas de bautismo por esta raz\u00f3n.<\/p>\n<ul>\n<li>Renunciamos a Satan\u00e1s y todo lo malo<\/li>\n<li>Creemos en Dios Padre Todo Poderoso, Creedor del cielo y toda la tierra<\/li>\n<li>Creemos en Jes\u00fas, su \u00fanico hijo nuestro Se\u00f1or, que naci\u00f3 de Santa Mar\u00eda Virgen, muri\u00f3, fue sepultado, resucit\u00f3 de entre los muertos y est\u00e1 sentado a la derecha del Padre<\/li>\n<li>\u00a0Creemos en el Esp\u00edritu Santo, en la Santa Iglesia Cat\u00f3lica, en la comuni\u00f3n de los santos, en el perd\u00f3n de los pecados, en la resurrecci\u00f3n del cuerpo y en la vida eterna<\/li>\n<\/ul>\n<p>Ahora, como siempre es importante salir a cumplir con estas promesas en nuestras vidas.\u00a0 Tambi\u00e9n es tiempo para disfrutar la belleza de esta temporada.\u00a0 En este tiempo celebramos los sacramentos de confirmaci\u00f3n y primera comuni\u00f3n en nuestras parroquias. Nos vestimos de blanco, las flores brotan y los pajaritos cantan.\u00a0 Como dice el pastor de nuestra iglesia (en referencia a Mateo 17,4) \u201cQue bueno que estemos aqu\u00ed!\u201d<\/p>\n<p>\u00a1Feliz Pascua!<\/p>\n<p><a href=\"http:\/\/www.austincnm.com\/index.php\/2012\/04\/estamos-muy-contentos\/118411_easter_lilly__3\/\" rel=\"attachment wp-att-14691\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14691\" title=\"118411_easter_lilly__3\" src=\"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2012\/04\/118411_easter_lilly__3.jpg?resize=100%2C75\" alt=\"\" width=\"100\" height=\"75\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta conversaci\u00f3n de Cantinflas en la pel\u00edcula El Padrecito siempre me da risa por la forma en que Cantinflas explica su buen humor.\u00a0 Acaba de llegar Cantinflas como el nuevo padrecito a un pueblo y Don Silvestre (el antagonista de la pel\u00edcula) lo quiere correr de ah\u00ed porque sabe que puede interrumpir sus malas intenciones&#8230;.&nbsp;<a href=\"https:\/\/atxcatholic.com\/index.php\/2012\/04\/estamos-muy-contentos\/\">[Read&nbsp;More]<\/a><\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[243,245],"tags":[85,438,712,330,713,714,711,606],"class_list":["post-14675","post","type-post","status-publish","format-standard","category-en-espanol","category-la-fe","tag-austin","tag-catolicos","tag-cristo","tag-jesus","tag-luz","tag-misa","tag-pascua","tag-resureccion","entry","has-post-thumbnail"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":12270,"url":"https:\/\/atxcatholic.com\/index.php\/2012\/02\/que-escuchas-tu\/","url_meta":{"origin":14675,"position":0},"title":"\u00bfQue Escuchas T\u00fa?","author":"Maria Salazar","date":"February 29, 2012","format":false,"excerpt":"Recuerdo hace unos anos, una amiga me cont\u00f3 algo de lo que no me olvidare.\u00a0 Me dijo que un d\u00eda su hermano se hab\u00eda subido a su coche y al mirar su colecci\u00f3n de CDs, le dijo \u201c\u00a1Ay mujer, con raz\u00f3n siempre andas deprimida!\u00a0 Mira todo lo que escuchas, Los\u2026","rel":"","context":"In &quot;En Espa\u00f1ol&quot;","block_context":{"text":"En Espa\u00f1ol","link":"https:\/\/atxcatholic.com\/index.php\/category\/acnm\/en-espanol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2012\/02\/Mariachi-300x199.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":27778,"url":"https:\/\/atxcatholic.com\/index.php\/2012\/12\/la-boda-de-oro-de-mis-padres\/","url_meta":{"origin":14675,"position":1},"title":"La Boda de Oro de Mis Padres","author":"Maria Salazar","date":"December 5, 2012","format":false,"excerpt":"Estamos haciendo planes para la celebraci\u00f3n de los 50 a\u00f1os de matrimonio de mis padres. \u00a050 a\u00f1os . . . si, algo que no es tan com\u00fan en el mundo en que vivimos ahora. \u00a0Gracias a Dios si hemos celebrado otras bodas de Oro entre la familia y amigos, pero\u2026","rel":"","context":"In &quot;En Espa\u00f1ol&quot;","block_context":{"text":"En Espa\u00f1ol","link":"https:\/\/atxcatholic.com\/index.php\/category\/acnm\/en-espanol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2012\/12\/Mom-and-Dad-2-280x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":50145,"url":"https:\/\/atxcatholic.com\/index.php\/2014\/07\/para-mi-sobrina-en-el-dia-de-su-boda\/","url_meta":{"origin":14675,"position":2},"title":"Para mi sobrina en el d\u00eda de su boda","author":"Maria Salazar","date":"July 31, 2014","format":false,"excerpt":"Estas a punto de entrar a una de las aventuras m\u00e1s bellas de tu vida. Estoy muy feliz y contenta por esta ocasi\u00f3n. Podr\u00eda platicarte de c\u00f3mo te he visto crecer a trav\u00e9s de los a\u00f1os y todo eso pero estoy segura que tu mam\u00e1 y tu pap\u00e1 tendr\u00e1n bastante\u2026","rel":"","context":"In &quot;La Fe&quot;","block_context":{"text":"La Fe","link":"https:\/\/atxcatholic.com\/index.php\/category\/acnm\/en-espanol\/la-fe\/"},"img":{"alt_text":"Boda","src":"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2014\/07\/photo-525x700.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":15518,"url":"https:\/\/atxcatholic.com\/index.php\/2012\/04\/primera-comunion\/","url_meta":{"origin":14675,"position":3},"title":"Primera Comuni\u00f3n","author":"Maria Salazar","date":"April 25, 2012","format":false,"excerpt":"Este Mayo, nuestra \u00fanica hija har\u00e1 su Primera Comuni\u00f3n.\u00a0 Creo estamos igual de emocionados los tres \u2013 mi esposo, mi hija, y yo. \u00a0\u00a0En otra ocasi\u00f3n les platico acerca de esta familia chica y nuestras esperanzas de tener m\u00e1s hijos.\u00a0 Sera por que somos tan peque\u00f1a familia, que nos encanta\u2026","rel":"","context":"In &quot;En Espa\u00f1ol&quot;","block_context":{"text":"En Espa\u00f1ol","link":"https:\/\/atxcatholic.com\/index.php\/category\/acnm\/en-espanol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2012\/04\/sacramentals-200x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":236380,"url":"https:\/\/atxcatholic.com\/index.php\/2016\/04\/el-proposito-de-su-vida\/","url_meta":{"origin":14675,"position":4},"title":"El prop\u00f3sito de su vida","author":"William Rooney","date":"April 13, 2016","format":false,"excerpt":"\u00bfCu\u00e1l es el prop\u00f3sito de su vida? Esta es una pregunta que todos debemos hacernos si queremos ser felices. Como humanos buscamos una raz\u00f3n para nuestra vida, algo que dar\u00e1 significado a nuestros d\u00edas aqu\u00ed. No estamos satisfechos con la realidad que encontramos cada d\u00eda, manchada con sufrimiento, violencia, dolor,\u2026","rel":"","context":"In &quot;En Espa\u00f1ol&quot;","block_context":{"text":"En Espa\u00f1ol","link":"https:\/\/atxcatholic.com\/index.php\/category\/acnm\/en-espanol\/"},"img":{"alt_text":"The Conversion of St. Augustine by Fra Angelico","src":"https:\/\/i0.wp.com\/atxcatholic.com\/wp-content\/uploads\/2014\/08\/augustine.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":41589,"url":"https:\/\/atxcatholic.com\/index.php\/2013\/09\/nuestra-comunidad-cristiana\/","url_meta":{"origin":14675,"position":5},"title":"Nuestra Comunidad Cristiana","author":"Maria Salazar","date":"September 21, 2013","format":false,"excerpt":"Nos necesitamos unos a los otros. Desde los primeros cristianos, se han formado comunidades, para celebrar la misa y seguir el camino de Cristo juntos.\u00a0 El Papa Francisco nos acaba de hablar de las ense\u00f1anzas de la iglesia en su reciente entrevista, incluso de este tema. \u201cLa pertenencia a un\u2026","rel":"","context":"In &quot;En Espa\u00f1ol&quot;","block_context":{"text":"En Espa\u00f1ol","link":"https:\/\/atxcatholic.com\/index.php\/category\/acnm\/en-espanol\/"},"img":{"alt_text":"La cruz de una iglesia, siempre visible para los fieles.","src":"https:\/\/i0.wp.com\/www.austincnm.com\/wp-content\/uploads\/2013\/09\/Mission-wood-cross.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/posts\/14675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/comments?post=14675"}],"version-history":[{"count":0,"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/posts\/14675\/revisions"}],"wp:attachment":[{"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/media?parent=14675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/categories?post=14675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atxcatholic.com\/index.php\/wp-json\/wp\/v2\/tags?post=14675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}